{"id":121,"date":"2023-11-14T02:56:57","date_gmt":"2023-11-14T02:56:57","guid":{"rendered":"https:\/\/demo.bravisthemes.com\/ducatibox\/?page_id=121"},"modified":"2026-06-27T14:51:29","modified_gmt":"2026-06-27T14:51:29","slug":"home","status":"publish","type":"page","link":"https:\/\/heuvelparts.com\/it\/","title":{"rendered":"Casa - Dettaglio auto"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"121\" class=\"elementor elementor-121\" data-elementor-post-type=\"page\">\n\t\t\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-7614cee elementor-section-full_width elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-section-offset-none pxl-section-smoke_particles-no pxl-row-scroll-none\" data-id=\"7614cee\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1914004 pxl-column-element-default pxl-column-none\" data-id=\"1914004\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-0ee3d51 elementor-widget elementor-widget-pxl_slider\" data-id=\"0ee3d51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"pxl-swiper-sliders pxl-element-slider pxl-swiper-nogap\" data-slider-mode=\"fade\">\n        <div class=\"pxl-carousel-inner\">\n            <div class=\"pxl-swiper-container\" dir=\"ltr\" data-settings=\"{&quot;slide_direction&quot;:&quot;horizontal&quot;,&quot;slide_percolumn&quot;:&quot;1&quot;,&quot;slide_mode&quot;:&quot;fade&quot;,&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_xxl&quot;:&quot;1&quot;,&quot;slides_to_show_lg&quot;:&quot;1&quot;,&quot;slides_to_show_md&quot;:&quot;1&quot;,&quot;slides_to_show_sm&quot;:&quot;1&quot;,&quot;slides_to_show_xs&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrow&quot;:&quot;false&quot;,&quot;pagination&quot;:&quot;false&quot;,&quot;pagination_type&quot;:&quot;bullets&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause_on_hover&quot;:&quot;&quot;,&quot;pause_on_interaction&quot;:&quot;true&quot;,&quot;delay&quot;:&quot;3000&quot;,&quot;loop&quot;:&quot;true&quot;,&quot;speed&quot;:&quot;400&quot;}\">\n                <div class=\"pxl-swiper-wrapper\">\n                                                <div class=\"pxl-swiper-slide\">\n                                <div class=\"pxl-slider--inner elementor-repeater-item-3e52d39\">\n                                    \n                                    <div class=\"pxl-slider--overlay bg-image elementor-repeater-item-3e52d39\"><\/div>\n\n                                    <div class=\"pxl-slider--content\">\n                                        \t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6299\" class=\"elementor elementor-6299\" data-elementor-post-type=\"pxl-template\">\n\t\t\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-9acc8cf elementor-section-full_width elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-section-offset-none pxl-section-smoke_particles-no pxl-row-scroll-none\" data-id=\"9acc8cf\" data-element_type=\"section\" data-e-type=\"section\">\n\n        <div class=\"pxl-section-bg-parallax\" data-parallax=\"{&quot;y&quot;:50}\"><\/div>                    <div class=\"elementor-background-overlay\"><\/div>\n            \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65132ed pxl-column-element-default pxl-column-none\" data-id=\"65132ed\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-49c04fb elementor-widget__width-auto elementor-absolute e-transform elementor-widget elementor-widget-pxl_image\" data-id=\"49c04fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-180,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:-50,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_laptop&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-image-single pxl-image-spin-rv\" data-wow-delay=\"ms\">\r\n                                        <div class=\"pxl-item--inner\">\r\n                                            <img fetchpriority=\"high\" decoding=\"async\" width=\"398\" height=\"398\" src=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2024\/01\/wheel-1-min.png\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                    <\/div>\r\n                        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t        <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-50dcc18 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-section-smoke_particles-no pxl-row-scroll-none\" data-id=\"50dcc18\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e562bb6 pxl-column-element-default pxl-column-none\" data-id=\"e562bb6\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-4e48ff5 elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-pxl_image\" data-id=\"4e48ff5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-image-single pxl-bottom-to-top\" data-wow-delay=\"ms\">\r\n                                        <div class=\"pxl-item--inner\">\r\n                                            <img decoding=\"async\" width=\"115\" height=\"159\" src=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2024\/01\/Shape-dotted-grid-blue.png\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                    <\/div>\r\n                        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52aa88b elementor-widget elementor-widget-pxl_heading\" data-id=\"52aa88b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_heading-52aa88b-3630\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t\t\t\t<div class=\"pxl-item--subtitle px-sub-title-default wow fadeInRight\" data-wow-delay=\"ms\">\n\t\t\t\t<span class=\"pxl-item--subtext\">\n\t\t\t\t\t\t\t\t\t\tHEUVELPARTS.COM \t\t\t\t\t<span class=\"pxl-item--subdivider\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t<h3 class=\"pxl-item--title wow fadeInRight\" data-wow-delay=\"ms\">\n\t\t\t\t\t\t\tIl vostro partner affidabile per tutti i ricambi\t\t\n\t\t\t\t\n\t\t<\/h3>\n\n\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec04719 elementor-widget elementor-widget-pxl_button_theme\" data-id=\"ec04719\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_button_theme.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-button-theme\">\r\n    <a class=\"btn  wow fadeInRight\" href=\"index.php\/webshop\" data-wow-delay=\"ms\">\r\n                <span class=\"pxl--btn-text\" data-text=\"NU WINKELEN\">\r\n            ACQUISTA ORA        <\/span>\r\n        <i class=\"pxl-icon-plus\"><\/i>\r\n    <\/a>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t                                    <\/div>\n                               <\/div>\n                            <\/div>\n                                                                        <div class=\"pxl-swiper-slide\">\n                                <div class=\"pxl-slider--inner elementor-repeater-item-99fba1f\">\n                                    \n                                    <div class=\"pxl-slider--overlay bg-image elementor-repeater-item-99fba1f\"><\/div>\n\n                                    <div class=\"pxl-slider--content\">\n                                        \t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6308\" class=\"elementor elementor-6308\" data-elementor-post-type=\"pxl-template\">\n\t\t\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-9acc8cf elementor-section-full_width elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-section-offset-none pxl-section-smoke_particles-no pxl-row-scroll-none\" data-id=\"9acc8cf\" data-element_type=\"section\" data-e-type=\"section\">\n\n        <div class=\"pxl-section-bg-parallax\" data-parallax=\"{&quot;y&quot;:50}\"><\/div>                    <div class=\"elementor-background-overlay\"><\/div>\n            \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65132ed pxl-column-element-default pxl-column-none\" data-id=\"65132ed\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-49c04fb elementor-widget__width-auto elementor-absolute e-transform elementor-widget elementor-widget-pxl_image\" data-id=\"49c04fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-180,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:-50,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_laptop&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-image-single pxl-image-spin-rv\" data-wow-delay=\"ms\">\r\n                                        <div class=\"pxl-item--inner\">\r\n                                            <img fetchpriority=\"high\" decoding=\"async\" width=\"398\" height=\"398\" src=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2024\/01\/wheel-1-min.png\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                    <\/div>\r\n                        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t        <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-50dcc18 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-section-smoke_particles-no pxl-row-scroll-none\" data-id=\"50dcc18\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e562bb6 pxl-column-element-default pxl-column-none\" data-id=\"e562bb6\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-4e48ff5 elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-pxl_image\" data-id=\"4e48ff5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-image-single pxl-bottom-to-top\" data-wow-delay=\"ms\">\r\n                                        <div class=\"pxl-item--inner\">\r\n                                            <img decoding=\"async\" width=\"115\" height=\"159\" src=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2024\/01\/Shape-dotted-grid-blue.png\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                    <\/div>\r\n                        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52aa88b elementor-widget elementor-widget-pxl_heading\" data-id=\"52aa88b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_heading-52aa88b-7248\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t\t\t\t<div class=\"pxl-item--subtitle px-sub-title-default wow fadeInRight\" data-wow-delay=\"ms\">\n\t\t\t\t<span class=\"pxl-item--subtext\">\n\t\t\t\t\t\t\t\t\t\tCONSIGLIO KUNDIG\t\t\t\t\t<span class=\"pxl-item--subdivider\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t<h3 class=\"pxl-item--title wow fadeInRight\" data-wow-delay=\"ms\">\n\t\t\t\t\t\t\tI nostri esperti sono pronti a fornirvi la migliore consulenza\t\t\n\t\t\t\t\n\t\t<\/h3>\n\n\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec04719 elementor-widget elementor-widget-pxl_button_theme\" data-id=\"ec04719\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_button_theme.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-button-theme\">\r\n    <a class=\"btn  wow fadeInRight\" href=\"index.php\/contatti\" data-wow-delay=\"ms\">\r\n                <span class=\"pxl--btn-text\" data-text=\"Contact Opnemen\">\r\n            Contattateci        <\/span>\r\n        <i class=\"pxl-icon-plus\"><\/i>\r\n    <\/a>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t                                    <\/div>\n                               <\/div>\n                            <\/div>\n                                                                        <div class=\"pxl-swiper-slide\">\n                                <div class=\"pxl-slider--inner elementor-repeater-item-64fd1bc\">\n                                    \n                                    <div class=\"pxl-slider--overlay bg-image elementor-repeater-item-64fd1bc\"><\/div>\n\n                                    <div class=\"pxl-slider--content\">\n                                        \t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6313\" class=\"elementor elementor-6313\" data-elementor-post-type=\"pxl-template\">\n\t\t\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-9acc8cf elementor-section-full_width elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-section-offset-none pxl-section-smoke_particles-no pxl-row-scroll-none\" data-id=\"9acc8cf\" data-element_type=\"section\" data-e-type=\"section\">\n\n        <div class=\"pxl-section-bg-parallax\" data-parallax=\"{&quot;y&quot;:50}\"><\/div>                    <div class=\"elementor-background-overlay\"><\/div>\n            \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65132ed pxl-column-element-default pxl-column-none\" data-id=\"65132ed\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-49c04fb elementor-widget__width-auto elementor-absolute e-transform elementor-widget elementor-widget-pxl_image\" data-id=\"49c04fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-180,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:-50,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_laptop&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-image-single pxl-image-spin-rv\" data-wow-delay=\"ms\">\r\n                                        <div class=\"pxl-item--inner\">\r\n                                            <img fetchpriority=\"high\" decoding=\"async\" width=\"398\" height=\"398\" src=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2024\/01\/wheel-1-min.png\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                    <\/div>\r\n                        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t        <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-50dcc18 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-section-smoke_particles-no pxl-row-scroll-none\" data-id=\"50dcc18\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e562bb6 pxl-column-element-default pxl-column-none\" data-id=\"e562bb6\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-4e48ff5 elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-pxl_image\" data-id=\"4e48ff5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-image-single pxl-bottom-to-top\" data-wow-delay=\"ms\">\r\n                                        <div class=\"pxl-item--inner\">\r\n                                            <img decoding=\"async\" width=\"115\" height=\"159\" src=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2024\/01\/Shape-dotted-grid-blue.png\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                    <\/div>\r\n                        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52aa88b elementor-widget elementor-widget-pxl_heading\" data-id=\"52aa88b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_heading-52aa88b-8153\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t\t\t\t<div class=\"pxl-item--subtitle px-sub-title-default wow fadeInRight\" data-wow-delay=\"ms\">\n\t\t\t\t<span class=\"pxl-item--subtext\">\n\t\t\t\t\t\t\t\t\t\tSTILE, MESSA A PUNTO E PARTI DI RICAMBIO DI QUALIT\u00c0 SUPERIORE\t\t\t\t\t<span class=\"pxl-item--subdivider\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t<h3 class=\"pxl-item--title wow fadeInRight\" data-wow-delay=\"ms\">\n\t\t\t\t\t\t\tNoi di Heuvelparts.com siamo sinonimo di qualit\u00e0 superiore.\t\t\n\t\t\t\t\n\t\t<\/h3>\n\n\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec04719 elementor-widget elementor-widget-pxl_button_theme\" data-id=\"ec04719\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_button_theme.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-button-theme\">\r\n    <a class=\"btn  wow fadeInRight\" href=\"index.php\/webshop\" data-wow-delay=\"ms\">\r\n                <span class=\"pxl--btn-text\" data-text=\"NU WINKELEN\">\r\n            ACQUISTA ORA        <\/span>\r\n        <i class=\"pxl-icon-plus\"><\/i>\r\n    <\/a>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t                                    <\/div>\n                               <\/div>\n                            <\/div>\n                                                            <\/div>\n            <\/div>\n        <\/div>\n\n        \n                    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-9267510 elementor-section-full_width elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-section-offset-none pxl-section-smoke_particles-no pxl-row-scroll-none\" data-id=\"9267510\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aecb637 pxl-column-element-default pxl-column-none\" data-id=\"aecb637\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-d61f90d elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-pxl_image\" data-id=\"d61f90d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-image-single slide-top-to-bottom\" data-wow-delay=\"ms\">\r\n                                        <div class=\"pxl-item--inner\">\r\n                                            <img decoding=\"async\" width=\"89\" height=\"158\" src=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2025\/11\/arrow-dow2.png\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                    <\/div>\r\n                        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t        <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-81b9d0c elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-section-smoke_particles-no pxl-row-scroll-none\" data-id=\"81b9d0c\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9c47aeb pxl-column-element-default pxl-column-none\" data-id=\"9c47aeb\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-edea378 elementor-widget elementor-widget-pxl_heading\" data-id=\"edea378\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_heading-edea378-6081\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t\t\t\t<div class=\"pxl-item--subtitle px-sub-title-default\" data-wow-delay=\"ms\">\n\t\t\t\t<span class=\"pxl-item--subtext\">\n\t\t\t\t\t\t\t\t\t\tI NOSTRI SERVIZI E PRODOTTI\t\t\t\t\t<span class=\"pxl-item--subdivider\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t<h3 class=\"pxl-item--title pxl-split-text split-in-left\" data-wow-delay=\"ms\">\n\t\t\t\t\t\t\tLe parti migliori\t\t\n\t\t\t\t\n\t\t<\/h3>\n\n\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba9dc60 elementor-widget elementor-widget-pxl_heading\" data-id=\"ba9dc60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_heading-ba9dc60-4819\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t\n\t\t<h3 class=\"pxl-item--title pxl-split-text split-in-left\" data-wow-delay=\"ms\">\n\t\t\t\t\t\t\tI prezzi pi\u00f9 alti\t\t\n\t\t\t\t\n\t\t<\/h3>\n\n\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"px-divider--wrap\">\n\t\t\t\t<div class=\"px-title--divider px-title--divider6\"><span><\/span><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8872094 pxl-column-element-default pxl-column-none\" data-id=\"8872094\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap\">\r\n                     \r\n                    <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-06509f1 elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-pxl_horizontal_scroll\" data-id=\"06509f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_horizontal_scroll.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t<div class=\"pxl-horizontal-scroll\">\r\n\t\t<div class=\"scroll-trigger gals-wrap\">\r\n\t\t\t\t\t<div class=\"gal-item\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"485\" src=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2024\/01\/bg-scoll-1.png\" class=\"attachment-full\" alt=\"\" \/><\/div>\t \r\n\t\t\t\t\t<div class=\"gal-item\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"485\" src=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2024\/01\/bg-scoll2.png\" class=\"attachment-full\" alt=\"\" \/><\/div>\t \r\n\t\t\t\t\t<div class=\"gal-item\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"485\" src=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2024\/01\/bg-scoll3.png\" class=\"attachment-full\" alt=\"\" \/><\/div>\t \r\n\t\t\t\t<\/div>\r\n\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-7850eef bg-darklight2 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-section-smoke_particles-no pxl-row-scroll-none\" data-id=\"7850eef\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dddfa74 pxl-column-element-default pxl-column-none\" data-id=\"dddfa74\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-932a5ae elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"932a5ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-97dc6d9 e-flex e-con-boxed e-con e-parent\" data-id=\"97dc6d9\" data-element_type=\"container\" data-e-type=\"container\">\t\t\t<div class=\"e-con-inner\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-aab96cf elementor-section-full_width bg-darklight2 elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-section-offset-none pxl-section-smoke_particles-no pxl-row-scroll-none\" data-id=\"aab96cf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e5cbc3 pxl-column-element-default pxl-column-none\" data-id=\"1e5cbc3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-2a8138a elementor-widget__width-auto elementor-absolute light-none e-transform elementor-widget elementor-widget-pxl_image\" data-id=\"2a8138a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;-50&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_laptop&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;-50&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_laptop&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-image-single pxl-bottom-to-top\" data-wow-delay=\"ms\">\r\n                                        <div class=\"pxl-item--inner\">\r\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"1304\" height=\"1235\" src=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2023\/12\/Ellipse-holder.png\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                    <\/div>\r\n                        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f37b41a elementor-widget elementor-widget-pxl_banner_box\" data-id=\"f37b41a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_banner_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-banner pxl-banner1\" data-wow-delay=\"ms\">\r\n\t<div class=\"pxl-banner-inner\">\r\n\t\t<div class=\"pxl-box-main\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t        <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-81a0dc6 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-section-smoke_particles-no pxl-row-scroll-none\" data-id=\"81a0dc6\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1a4aea8 pxl-column-element-default pxl-column-none\" data-id=\"1a4aea8\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-3ca70ff elementor-widget elementor-widget-image\" data-id=\"3ca70ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"396\" height=\"905\" src=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2025\/11\/gtr-1c.png\" class=\"attachment-large size-large wp-image-8624\" alt=\"\" srcset=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2025\/11\/gtr-1c.png 396w, https:\/\/heuvelparts.com\/wp-content\/uploads\/2025\/11\/gtr-1c-131x300.png 131w, https:\/\/heuvelparts.com\/wp-content\/uploads\/2025\/11\/gtr-1c-311x710.png 311w\" sizes=\"(max-width: 396px) 100vw, 396px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7da3c91 pxl-column-element-default pxl-column-none\" data-id=\"7da3c91\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-2152c64 elementor-widget__width-auto elementor-widget elementor-widget-pxl_image\" data-id=\"2152c64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-image-single  wow rotateInDownRight\" data-wow-delay=\"ms\">\r\n                                        <div class=\"pxl-item--inner\">\r\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"97\" height=\"39\" src=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2025\/11\/wrench2.png\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                    <\/div>\r\n                        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a82b6f8 elementor-widget elementor-widget-pxl_heading\" data-id=\"a82b6f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_heading-a82b6f8-9190\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t\n\t\t<h3 class=\"pxl-item--title\" data-wow-delay=\"ms\">\n\t\t\t\t\t\t\tIl vostro veicolo esattamente\ncome lo volete voi\t\t\n\t\t\t\t\n\t\t<\/h3>\n\n\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f519a28 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"f519a28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>Che si tratti della migliore consulenza o dei migliori ricambi al prezzo pi\u00f9 competitivo, noi pensiamo insieme a voi. Insieme, ci assicuriamo che il vostro veicolo diventi e rimanga esattamente come lo desiderate.\u00a0<\/p>\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b748a1 elementor-widget elementor-widget-pxl_button_theme\" data-id=\"3b748a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_button_theme.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-button-theme\">\r\n    <a class=\"btn\" href=\"https:\/\/heuvelparts.com\/it\/contatto\/\" data-wow-delay=\"ms\">\r\n                <span class=\"pxl--btn-text\" data-text=\"Contact Opnemen\">\r\n            Contattateci        <\/span>\r\n        <i class=\"pxl-icon-plus\"><\/i>\r\n    <\/a>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f2527e elementor-section-full_width elementor-section-stretched bg-darklight2 elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-section-offset-none pxl-section-smoke_particles-no pxl-row-scroll-none\" data-id=\"4f2527e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-no\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d2dac1 pxl-column-element-default pxl-column-none\" data-id=\"5d2dac1\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-18d13e0 e-transform elementor-widget elementor-widget-pxl_text_slip\" data-id=\"18d13e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;-8&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;10&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_laptop&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"pxl_text_slip.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"pxl-text-slip pxl-text-slip1 pxl-slide-to-right  pxl-text-white-shadow\" data-wow-delay=\"ms\">\n\t\t<div class=\"pxl-item--container\">\n\t\t\t<div class=\"pxl-item--inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\t\n\t\t\t\t\t<span class=\"pxl-text-backdrop\">INTERNO<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\t\n\t\t\t\t\t<span class=\"pxl-text-backdrop\">STILE<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\t\n\t\t\t\t\t<span class=\"pxl-text-backdrop\">PARTI PREMIUM<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\t\n\t\t\t\t\t<span class=\"pxl-text-backdrop\">VEICOLI<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\t\n\t\t\t\t\t<span class=\"pxl-text-backdrop\">SINTONIZZAZIONE<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"pxl-item--inner\" >\n\t\t\t\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\n\t\t\t\t<span class=\"pxl-text-backdrop\">INTERNO<\/span>\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\n\t\t\t\t<span class=\"pxl-text-backdrop\">STILE<\/span>\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\n\t\t\t\t<span class=\"pxl-text-backdrop\">PARTI PREMIUM<\/span>\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\n\t\t\t\t<span class=\"pxl-text-backdrop\">VEICOLI<\/span>\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\n\t\t\t\t<span class=\"pxl-text-backdrop\">SINTONIZZAZIONE<\/span>\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8883ec7 elementor-absolute elementor-widget elementor-widget-pxl_text_slip\" data-id=\"8883ec7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_text_slip.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"pxl-text-slip pxl-text-slip1 pxl-slide-to-left  pxl-text-white-shadow\" data-wow-delay=\"ms\">\n\t\t<div class=\"pxl-item--container\">\n\t\t\t<div class=\"pxl-item--inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\t\n\t\t\t\t\t<span class=\"pxl-text-backdrop\">INTERNO<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\t\n\t\t\t\t\t<span class=\"pxl-text-backdrop\">SINTONIZZAZIONE CHIP<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\t\n\t\t\t\t\t<span class=\"pxl-text-backdrop\">AVVOLGIMENTO<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\t\n\t\t\t\t\t<span class=\"pxl-text-backdrop\">PARTI<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\t\n\t\t\t\t\t<span class=\"pxl-text-backdrop\">STILE<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\t\n\t\t\t\t\t<span class=\"pxl-text-backdrop\">PERSONALIZZAZIONE<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\t\n\t\t\t\t\t<span class=\"pxl-text-backdrop\">PARERE<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"pxl-item--inner\" >\n\t\t\t\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\n\t\t\t\t<span class=\"pxl-text-backdrop\">INTERNO<\/span>\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\n\t\t\t\t<span class=\"pxl-text-backdrop\">SINTONIZZAZIONE CHIP<\/span>\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\n\t\t\t\t<span class=\"pxl-text-backdrop\">AVVOLGIMENTO<\/span>\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\n\t\t\t\t<span class=\"pxl-text-backdrop\">PARTI<\/span>\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\n\t\t\t\t<span class=\"pxl-text-backdrop\">STILE<\/span>\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\n\t\t\t\t<span class=\"pxl-text-backdrop\">PERSONALIZZAZIONE<\/span>\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<h4 class=\"pxl-item--text\">\t\t\t\t\n\t\t\t\t<span class=\"pxl-text-backdrop\">PARERE<\/span>\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-icon-5\"><\/i>\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-5fee119 bg-darklight2 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-section-smoke_particles-no pxl-row-scroll-none\" data-id=\"5fee119\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7253a8f pxl-column-element-default pxl-column-none\" data-id=\"7253a8f\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-49ca378 elementor-widget elementor-widget-pxl_heading\" data-id=\"49ca378\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_heading-49ca378-5639\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t\t\t\t<div class=\"pxl-item--subtitle px-sub-title-default\" data-wow-delay=\"ms\">\n\t\t\t\t<span class=\"pxl-item--subtext\">\n\t\t\t\t\t\t\t\t\t\tLA NOSTRA PROMESSA\t\t\t\t\t<span class=\"pxl-item--subdivider\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t<h3 class=\"pxl-item--title pxl-split-text split-in-left\" data-wow-delay=\"ms\">\n\t\t\t\t\t\t\tPerch\u00e9 scegliere <cite>Heuvelparts<\/cite>\t\t\n\t\t\t\t\n\t\t<\/h3>\n\n\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"px-divider--wrap\">\n\t\t\t\t<div class=\"px-title--divider px-title--divider6\"><span><\/span><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-695319b e-flex e-con-boxed e-con e-parent\" data-id=\"695319b\" data-element_type=\"container\" data-e-type=\"container\">\t\t\t<div class=\"e-con-inner\">\r\n\t\t<div class=\"elementor-element elementor-element-1116418 e-con-full e-flex e-con e-child\" data-id=\"1116418\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-7fc305d elementor-widget elementor-widget-image\" data-id=\"7fc305d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"796\" height=\"1024\" src=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2025\/11\/Gemini_Generated_Image_c4owrc4owrc4owrc-796x1024.png\" class=\"attachment-large size-large wp-image-8677\" alt=\"\" srcset=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2025\/11\/Gemini_Generated_Image_c4owrc4owrc4owrc-796x1024.png 796w, https:\/\/heuvelparts.com\/wp-content\/uploads\/2025\/11\/Gemini_Generated_Image_c4owrc4owrc4owrc-233x300.png 233w, https:\/\/heuvelparts.com\/wp-content\/uploads\/2025\/11\/Gemini_Generated_Image_c4owrc4owrc4owrc-768x987.png 768w, https:\/\/heuvelparts.com\/wp-content\/uploads\/2025\/11\/Gemini_Generated_Image_c4owrc4owrc4owrc-552x710.png 552w, https:\/\/heuvelparts.com\/wp-content\/uploads\/2025\/11\/Gemini_Generated_Image_c4owrc4owrc4owrc-600x771.png 600w, https:\/\/heuvelparts.com\/wp-content\/uploads\/2025\/11\/Gemini_Generated_Image_c4owrc4owrc4owrc.png 896w\" sizes=\"(max-width: 796px) 100vw, 796px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t<div class=\"elementor-element elementor-element-c5fdfb7 e-con-full e-flex e-con e-child\" data-id=\"c5fdfb7\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-7fc7cf4 elementor-widget elementor-widget-html\" data-id=\"7fc7cf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<section style=\"font-family:inherit;color:#ffffff;line-height:1.6;padding:40px 20px;max-width:900px;margin:0 auto\">\n\n  <h2 style=\"font-size:clamp(24px,2.5vw,32px);font-weight:800;margin:0 0 15px;text-align:center\">\n    Perch\u00e9 scegliere Heuvelparts?\n  <\/h2>\n\n  <p style=\"font-size:clamp(15px,1.2vw,18px);margin:0 0 12px;color:#e5e5e5;text-align:center\">\n    Ricambi di qualit\u00e0, styling, tuning e acquisto e vendita di veicoli: tutto sotto lo stesso tetto.\n  <\/p>\n\n  <div style=\"margin-top:30px;font-size:clamp(15px,1.2vw,17px);color:#d4d4d4\">\n\n    <p><strong style=\"color:#ffffff\">\u2714 Esperienza e competenza:<\/strong> Consulenza personalizzata grazie alla conoscenza pluriennale di marchi, ricambi e aggiornamenti delle prestazioni.<\/p>\n\n    <p><strong style=\"color:#ffffff\">Qualit\u00e0 premium:<\/strong> Componenti e prodotti affidabili che si adattano, funzionano e durano nel tempo.<\/p>\n\n    <p><strong style=\"color:#ffffff\">\u2714 Styling e tuning:<\/strong> Da piccoli aggiustamenti a trasformazioni complete, sempre eseguite in modo professionale ed elegante.<\/p>\n\n    <p><strong style=\"color:#ffffff\">\u2714 Acquisto e vendita di veicoli:<\/strong> Valutazione equa, accordi trasparenti e gestione rapida e senza intoppi.<\/p>\n\n    <p><strong style=\"color:#ffffff\">Comunicazione chiara:<\/strong> Linee brevi, servizio rapido e accordi chiari, come dovrebbe essere.<\/p>\n\n  <\/div>\n\n  <p style=\"margin-top:35px;text-align:center;font-size:clamp(16px,1.3vw,19px);color:#ffffff\">\n    <strong>Heuvelparts \u2014 il vostro partner di fiducia per ricambi, personalizzazione, tuning e vendita di veicoli.<\/strong>\n  <\/p>\n\n<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-a1325d3 bg-darklight2 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-section-smoke_particles-no pxl-row-scroll-none\" data-id=\"a1325d3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\n        <div class=\"pxl-section-bg-parallax\" data-parallax=\"{&quot;y&quot;:50}\"><\/div>        \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de0a8c1 pxl-column-element-default pxl-column-none\" data-id=\"de0a8c1\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n                <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-950e98c elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-section-smoke_particles-no pxl-row-scroll-none\" data-id=\"950e98c\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-no\">\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d382681 pxl-column-element-default pxl-column-none\" data-id=\"d382681\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-e1c87e9 elementor-widget elementor-widget-pxl_heading\" data-id=\"e1c87e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_heading-e1c87e9-1328\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t\t\t\t<div class=\"pxl-item--subtitle px-sub-title-default\" data-wow-delay=\"ms\">\n\t\t\t\t<span class=\"pxl-item--subtext\">\n\t\t\t\t\t\t\t\t\t\tRECENSIONI DEI CLIENTI\t\t\t\t\t<span class=\"pxl-item--subdivider\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t<h3 class=\"pxl-item--title pxl-split-text split-in-left\" data-wow-delay=\"ms\">\n\t\t\t\t\t\t\tCosa dicono i clienti di Heuvelparts\t\t\n\t\t\t\t\n\t\t<\/h3>\n\n\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"px-divider--wrap\">\n\t\t\t\t<div class=\"px-title--divider px-title--divider6\"><span><\/span><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0ccbba8 pxl-column-element-default pxl-column-none\" data-id=\"0ccbba8\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap\">\r\n                     \r\n                    <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad05ec8 elementor-widget elementor-widget-pxl_testimonial_carousel\" data-id=\"ad05ec8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_testimonial_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"pxl-swiper-sliders pxl-testimonial-carousel pxl-testimonial-carousel1 pxl-swiper-arrow-show bullets-middle-right\">\n        <div class=\"pxl-carousel-inner\">\n            <div class=\"pxl-swiper-container\" dir=\"ltr\" data-settings=\"{&quot;slide_direction&quot;:&quot;horizontal&quot;,&quot;slide_percolumn&quot;:&quot;1&quot;,&quot;slide_mode&quot;:&quot;slide&quot;,&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_xxl&quot;:&quot;1&quot;,&quot;slides_to_show_lg&quot;:&quot;1&quot;,&quot;slides_to_show_md&quot;:&quot;1&quot;,&quot;slides_to_show_sm&quot;:&quot;1&quot;,&quot;slides_to_show_xs&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrow&quot;:&quot;false&quot;,&quot;pagination&quot;:&quot;true&quot;,&quot;pagination_type&quot;:&quot;bullets&quot;,&quot;autoplay&quot;:&quot;&quot;,&quot;pause_on_hover&quot;:&quot;&quot;,&quot;pause_on_interaction&quot;:&quot;true&quot;,&quot;delay&quot;:5000,&quot;loop&quot;:&quot;false&quot;,&quot;speed&quot;:500,&quot;center&quot;:&quot;false&quot;}\">\n                <div class=\"pxl-swiper-wrapper\">\n                                            <div class=\"pxl-swiper-slide\">\n                            <div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n                                                                    <div class=\"pxl-item--image\">\n                                        <div class=\"inner-image\">\n                                            <img loading=\"lazy\" decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2023\/11\/client-1.jpg\" width=\"230\" height=\"230\" alt=\"cliente-1\" title=\"cliente-1\" \/>                                        <\/div>\n                                        <div class=\"pxl-quoters\">\n                                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"44\" height=\"36\" viewbox=\"0 0 44 36\" fill=\"none\">\n                                              <path d=\"M40.2219 30.1817C44.3187 25.7354 43.9062 20.0255 43.8932 19.9604V2.59195C43.8932 2.01615 43.6644 1.46394 43.2573 1.05679C42.8501 0.649634 42.2979 0.420898 41.7221 0.420898H28.6958C26.3011 0.420898 24.3537 2.36833 24.3537 4.763V19.9604C24.3537 20.5362 24.5824 21.0884 24.9896 21.4955C25.3967 21.9027 25.9489 22.1314 26.5247 22.1314H33.2072C33.1614 23.2048 32.8407 24.2483 32.2759 25.1622C31.173 26.9012 29.0953 28.0888 26.097 28.688L24.3537 29.0354V35.1577H26.5247C32.5668 35.1577 37.1759 33.4839 40.2219 30.1817ZM16.3251 30.1817C20.4241 25.7354 20.0094 20.0255 19.9964 19.9604V2.59195C19.9964 2.01615 19.7676 1.46394 19.3605 1.05679C18.9533 0.649634 18.4011 0.420898 17.8253 0.420898H4.79901C2.40434 0.420898 0.456909 2.36833 0.456909 4.763V19.9604C0.456909 20.5362 0.685644 21.0884 1.0928 21.4955C1.49995 21.9027 2.05216 22.1314 2.62796 22.1314H9.31046C9.26459 23.2048 8.94389 24.2483 8.37908 25.1622C7.27619 26.9012 5.19849 28.0888 2.20026 28.688L0.456909 29.0354V35.1577H2.62796C8.67 35.1577 13.2791 33.4839 16.3251 30.1817Z\"\/>\n                                            <\/svg>\n                                        <\/div>\n                                    <\/div>\n                                                                <div class=\"pxl-content\">\n                                                                            <span class=\"pxl-item--star pxl-item--5-star\">\n                                            <i class=\"bravisicon bravisicon-star\"><\/i>\n                                            <i class=\"bravisicon bravisicon-star\"><\/i>\n                                            <i class=\"bravisicon bravisicon-star\"><\/i>\n                                            <i class=\"bravisicon bravisicon-star\"><\/i>\n                                            <i class=\"bravisicon bravisicon-star\"><\/i>\n                                        <\/span>\n                                                                        <div class=\"pxl-item--desc el-empty\">Servizio fantastico! toppers con attrezzature moderne e veri professionisti. Hanno completamente personalizzato e messo a punto la mia Audi e il risultato \u00e8 davvero impressionante. La mia auto \u00e8 stata pronta prima del previsto e da allora guida perfettamente. Grazie, lo consiglio vivamente!<\/div>\n                                    <h4 class=\"pxl-item--title el-empty\">Hendrik Jansen<\/h4>\n                                    <div class=\"pxl-item--position el-empty\">Amsterdam<\/div>\n                                <\/div>\n                           <\/div>\n                        <\/div>\n                                            <div class=\"pxl-swiper-slide\">\n                            <div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n                                                                    <div class=\"pxl-item--image\">\n                                        <div class=\"inner-image\">\n                                            <img loading=\"lazy\" decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2023\/11\/team-v4-230x230.jpg\" width=\"230\" height=\"230\" alt=\"squadra-v4\" title=\"squadra-v4\" \/>                                        <\/div>\n                                        <div class=\"pxl-quoters\">\n                                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"44\" height=\"36\" viewbox=\"0 0 44 36\" fill=\"none\">\n                                              <path d=\"M40.2219 30.1817C44.3187 25.7354 43.9062 20.0255 43.8932 19.9604V2.59195C43.8932 2.01615 43.6644 1.46394 43.2573 1.05679C42.8501 0.649634 42.2979 0.420898 41.7221 0.420898H28.6958C26.3011 0.420898 24.3537 2.36833 24.3537 4.763V19.9604C24.3537 20.5362 24.5824 21.0884 24.9896 21.4955C25.3967 21.9027 25.9489 22.1314 26.5247 22.1314H33.2072C33.1614 23.2048 32.8407 24.2483 32.2759 25.1622C31.173 26.9012 29.0953 28.0888 26.097 28.688L24.3537 29.0354V35.1577H26.5247C32.5668 35.1577 37.1759 33.4839 40.2219 30.1817ZM16.3251 30.1817C20.4241 25.7354 20.0094 20.0255 19.9964 19.9604V2.59195C19.9964 2.01615 19.7676 1.46394 19.3605 1.05679C18.9533 0.649634 18.4011 0.420898 17.8253 0.420898H4.79901C2.40434 0.420898 0.456909 2.36833 0.456909 4.763V19.9604C0.456909 20.5362 0.685644 21.0884 1.0928 21.4955C1.49995 21.9027 2.05216 22.1314 2.62796 22.1314H9.31046C9.26459 23.2048 8.94389 24.2483 8.37908 25.1622C7.27619 26.9012 5.19849 28.0888 2.20026 28.688L0.456909 29.0354V35.1577H2.62796C8.67 35.1577 13.2791 33.4839 16.3251 30.1817Z\"\/>\n                                            <\/svg>\n                                        <\/div>\n                                    <\/div>\n                                                                <div class=\"pxl-content\">\n                                                                            <span class=\"pxl-item--star pxl-item--5-star\">\n                                            <i class=\"bravisicon bravisicon-star\"><\/i>\n                                            <i class=\"bravisicon bravisicon-star\"><\/i>\n                                            <i class=\"bravisicon bravisicon-star\"><\/i>\n                                            <i class=\"bravisicon bravisicon-star\"><\/i>\n                                            <i class=\"bravisicon bravisicon-star\"><\/i>\n                                        <\/span>\n                                                                        <div class=\"pxl-item--desc el-empty\">Un'esperienza eccellente! Ho ordinato diversi pezzi per la mia auto e tutto \u00e8 stato consegnato rapidamente e perfettamente imballato. La qualit\u00e0 \u00e8 ottima ed \u00e8 esattamente ci\u00f2 di cui avevo bisogno. La comunicazione \u00e8 stata chiara e cordiale. Sono super soddisfatto!<\/div>\n                                    <h4 class=\"pxl-item--title el-empty\">Brandon Kuijpers<\/h4>\n                                    <div class=\"pxl-item--position el-empty\">Boxtel<\/div>\n                                <\/div>\n                           <\/div>\n                        <\/div>\n                                            <div class=\"pxl-swiper-slide\">\n                            <div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n                                                                    <div class=\"pxl-item--image\">\n                                        <div class=\"inner-image\">\n                                            <img loading=\"lazy\" decoding=\"async\" class=\"no-lazyload\" src=\"https:\/\/heuvelparts.com\/wp-content\/uploads\/2023\/11\/team-v2-230x230.jpg\" width=\"230\" height=\"230\" alt=\"squadra-v2\" title=\"squadra-v2\" \/>                                        <\/div>\n                                        <div class=\"pxl-quoters\">\n                                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"44\" height=\"36\" viewbox=\"0 0 44 36\" fill=\"none\">\n                                              <path d=\"M40.2219 30.1817C44.3187 25.7354 43.9062 20.0255 43.8932 19.9604V2.59195C43.8932 2.01615 43.6644 1.46394 43.2573 1.05679C42.8501 0.649634 42.2979 0.420898 41.7221 0.420898H28.6958C26.3011 0.420898 24.3537 2.36833 24.3537 4.763V19.9604C24.3537 20.5362 24.5824 21.0884 24.9896 21.4955C25.3967 21.9027 25.9489 22.1314 26.5247 22.1314H33.2072C33.1614 23.2048 32.8407 24.2483 32.2759 25.1622C31.173 26.9012 29.0953 28.0888 26.097 28.688L24.3537 29.0354V35.1577H26.5247C32.5668 35.1577 37.1759 33.4839 40.2219 30.1817ZM16.3251 30.1817C20.4241 25.7354 20.0094 20.0255 19.9964 19.9604V2.59195C19.9964 2.01615 19.7676 1.46394 19.3605 1.05679C18.9533 0.649634 18.4011 0.420898 17.8253 0.420898H4.79901C2.40434 0.420898 0.456909 2.36833 0.456909 4.763V19.9604C0.456909 20.5362 0.685644 21.0884 1.0928 21.4955C1.49995 21.9027 2.05216 22.1314 2.62796 22.1314H9.31046C9.26459 23.2048 8.94389 24.2483 8.37908 25.1622C7.27619 26.9012 5.19849 28.0888 2.20026 28.688L0.456909 29.0354V35.1577H2.62796C8.67 35.1577 13.2791 33.4839 16.3251 30.1817Z\"\/>\n                                            <\/svg>\n                                        <\/div>\n                                    <\/div>\n                                                                <div class=\"pxl-content\">\n                                                                            <span class=\"pxl-item--star pxl-item--5-star\">\n                                            <i class=\"bravisicon bravisicon-star\"><\/i>\n                                            <i class=\"bravisicon bravisicon-star\"><\/i>\n                                            <i class=\"bravisicon bravisicon-star\"><\/i>\n                                            <i class=\"bravisicon bravisicon-star\"><\/i>\n                                            <i class=\"bravisicon bravisicon-star\"><\/i>\n                                        <\/span>\n                                                                        <div class=\"pxl-item--desc el-empty\">Heuvelparts.com mi ha aiutato in modo fantastico. Ero alla ricerca di ricambi di qualit\u00e0 per la mia Jeep e ho ricevuto una consulenza personalizzata davvero esperta. Hanno riflettuto con me, mi hanno spiegato tutto con chiarezza e mi hanno indicato esattamente i pezzi pi\u00f9 adatti alla mia configurazione. Grazie alle loro conoscenze e al loro servizio, sono riuscito a personalizzare la mia auto! Assolutamente un indirizzo eccellente!<\/div>\n                                    <h4 class=\"pxl-item--title el-empty\">Raymond Castillo<\/h4>\n                                    <div class=\"pxl-item--position el-empty\">Eindhoven<\/div>\n                                <\/div>\n                           <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                                        <div class=\"pxl-swiper-dots\"><\/div>\n                    <\/div>\n    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>.elementor-6299 .elementor-element.elementor-element-9acc8cf{overflow:hidden;padding:185px 0px 185px 0px;}.elementor-6299 .elementor-element.elementor-element-9acc8cf .pxl-section-bg-parallax{background-image:url( https:\/\/heuvelparts.com\/wp-content\/uploads\/2024\/01\/car-bg-slide1b.jpg );background-position:center center;background-size:cover;top:-50px;}.elementor-6299 .elementor-element.elementor-element-49c04fb{width:auto;max-width:auto;top:50%;}body:not(.rtl) .elementor-6299 .elementor-element.elementor-element-49c04fb{left:0px;}body.rtl .elementor-6299 .elementor-element.elementor-element-49c04fb{right:0px;}.elementor-6299 .elementor-element.elementor-element-49c04fb &gt; .elementor-widget-container{&#8211;e-transform-translateX:-180px;&#8211;e-transform-translateY:-50%;}.elementor-6299 .elementor-element.elementor-element-50dcc18{z-index:1;}.elementor-6299 .elementor-element.elementor-element-4e48ff5{width:auto;max-width:auto;top:-80px;}body:not(.rtl) .elementor-6299 .elementor-element.elementor-element-4e48ff5{left:-60px;}body.rtl .elementor-6299 .elementor-element.elementor-element-4e48ff5{right:-60px;}.elementor-6299 .elementor-element.elementor-element-52aa88b .pxl-heading .pxl-heading&#8211;inner{max-width:680px;}.elementor-6299 .elementor-element.elementor-element-52aa88b .pxl-heading .pxl-item&#8211;title{color:#FFFFFF;font-size:70px;line-height:70px;margin-bottom:0px;}.elementor-6299 .elementor-element.elementor-element-52aa88b .pxl-heading .pxl-item&#8211;subtitle{color:#FF0000;margin-bottom:30px;}.elementor-6299 .elementor-element.elementor-element-52aa88b &gt; .elementor-widget-container{margin:0px 0px 55px 0px;}.elementor-6299 .elementor-element.elementor-element-52aa88b{z-index:1;}.elementor-6299 .elementor-element.elementor-element-ec04719 .pxl-button-theme .btn i:before, .elementor-6299 .elementor-element.elementor-element-ec04719 .pxl-button-theme .btn i:after{color:#FFFFFF;}.elementor-6299 .elementor-element.elementor-element-ec04719 .pxl-button-theme .btn::before{background-color:#FF0000 !important;}.elementor-6299 .elementor-element.elementor-element-ec04719 .pxl-button-theme [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-121","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/heuvelparts.com\/it\/wp-json\/wp\/v2\/pages\/121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heuvelparts.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/heuvelparts.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/heuvelparts.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/heuvelparts.com\/it\/wp-json\/wp\/v2\/comments?post=121"}],"version-history":[{"count":127,"href":"https:\/\/heuvelparts.com\/it\/wp-json\/wp\/v2\/pages\/121\/revisions"}],"predecessor-version":[{"id":9234,"href":"https:\/\/heuvelparts.com\/it\/wp-json\/wp\/v2\/pages\/121\/revisions\/9234"}],"wp:attachment":[{"href":"https:\/\/heuvelparts.com\/it\/wp-json\/wp\/v2\/media?parent=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}