{"id":8851,"date":"2025-12-11T10:24:22","date_gmt":"2025-12-11T10:24:22","guid":{"rendered":"https:\/\/heuvelparts.com\/?page_id=8851"},"modified":"2025-12-11T10:27:03","modified_gmt":"2025-12-11T10:27:03","slug":"cookie-per-la-privacy","status":"publish","type":"page","link":"https:\/\/heuvelparts.com\/it\/cookie-per-la-privacy\/","title":{"rendered":"Privacy e cookie"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"8851\" class=\"elementor elementor-8851\" data-elementor-post-type=\"page\">\n\t\t\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-8429fb7 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-section-smoke_particles-no pxl-row-scroll-none\" data-id=\"8429fb7\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bb6a550 pxl-column-element-default pxl-column-none\" data-id=\"bb6a550\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-0656356 elementor-widget elementor-widget-html\" data-id=\"0656356\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<section class=\"privacy-policy\" style=\"font-family: 'Poppins', sans-serif; line-height: 1.6;\">\n  <div class=\"container\">\n\n    <h2>Informativa sulla privacy e sui cookie<\/h2>\n    <p><strong>Rob v\/d Heuvel Auto<\/strong><br>\n      Bedrijvenweg 16, 5272 PB SINT-MICHIELSGESTEL<br>\n      Camera di Commercio: 16052168<br>\n      Persona di contatto: Rob Heuvel<br>\n      E-mail: <a href=\"mailto:in**@*********ts.com\" data-original-string=\"ia\/2TZb+kQfEGYQJ+ZPt9A==8e7oyv3TSWH09N+eJkrCzUKzl21LwW3vxc8VCp7TneCu8Y=\" title=\"This contact has been encoded by Anti-Spam by CleanTalk. Click to decode. To finish the decoding make sure that JavaScript is enabled in your browser.\"><span \n                data-original-string='trzwgTAhFS1\/kbAzfhnfmA==8e79aOzIowH3UcRRpQHk0hR6W8hpFr0pb34lQo\/hPTowU0='\n                class='apbct-email-encoder'\n                title='This contact has been encoded by Anti-Spam by CleanTalk. Click to decode. To finish the decoding make sure that JavaScript is enabled in your browser.'>a<span class=\"apbct-blur\">**<\/span>@<span class=\"apbct-blur\">*********<\/span>ts.com<\/span><\/a><br>\n      Telefono: <a href=\"tel:+31640994248\">06 - 40 99 42 48<\/a><br>\n      Ultimo aggiornamento: dicembre 2025\n    <\/p>\n\n    <h3>1. Introduzione<\/h3>\n    <p>Rob v\/d Heuvel Auto's si impegna a proteggere la vostra privacy e i vostri dati personali. Trattiamo i vostri dati esclusivamente in conformit\u00e0 al Regolamento Generale sulla Protezione dei Dati (RGPD) e ad altre leggi.<\/p>\n    <p>Questo include:<\/p>\n    <ul>\n      <li>Indicare chiaramente le finalit\u00e0 per cui trattiamo i dati personali;<\/li>\n      <li>Elaborare solo i dati necessari;<\/li>\n      <li>Richiedere il consenso, ove necessario;<\/li>\n      <li>Non condividiamo i vostri dati con terzi, a meno che non sia necessario o richiesto dalla legge;<\/li>\n      <li>stipulare accordi di elaborazione con soggetti che trattano i dati per nostro conto;<\/li>\n      <li>Implementare misure di sicurezza adeguate;<\/li>\n      <li>Rispettare i diritti dell'utente, quali l'ispezione, la rettifica e la cancellazione;<\/li>\n      <li>Utilizzare i cookie solo con il consenso o quando \u00e8 necessario.<\/li>\n    <\/ul>\n\n    <h3>2. Quali dati personali trattiamo?<\/h3>\n    <p>Possiamo trattare i seguenti dati:<\/p>\n    <h4>Dati dei contatti e dei clienti<\/h4>\n    <ul>\n      <li>Nome<\/li>\n      <li>Indirizzo, codice postale e citt\u00e0<\/li>\n      <li>Numero di telefono<\/li>\n      <li>Indirizzo e-mail<\/li>\n      <li>Numero di registrazione (se fornito)<\/li>\n    <\/ul>\n\n    <h4>Sito web e dati degli utenti<\/h4>\n    <ul>\n      <li>Indirizzo IP (possibilmente anonimo)<\/li>\n      <li>Dati del browser e del dispositivo<\/li>\n      <li>Comportamento in surf<\/li>\n      <li>Biscotti<\/li>\n    <\/ul>\n\n    <h4>Dati da moduli<\/h4>\n    <p>Quando compilate un modulo di contatto, trattiamo i dati che ci fornite per contattarvi.<\/p>\n\n    <h4>File di log<\/h4>\n    <p>Il nostro server registra i dati di log per garantire il funzionamento sicuro e stabile del sito web.<\/p>\n\n    <h3>3. Finalit\u00e0 e basi<\/h3>\n    <p>Trattiamo i vostri dati personali per le seguenti finalit\u00e0:<\/p>\n    <h4>3.1 Contatti e servizio clienti<\/h4>\n    <p>Per rispondere alle domande e fissare appuntamenti.<br><strong>Base:<\/strong> interesse legittimo ed esecuzione di un contratto.<\/p>\n\n    <h4>3.2 Gare d'appalto e fornitura di servizi<\/h4>\n    <p>Per la preparazione e l'esecuzione di offerte e servizi.<br><strong>Base:<\/strong> l'esecuzione di un accordo.<\/p>\n\n    <h4>3.3 Migliorare il nostro sito web<\/h4>\n    <p>Utilizziamo dati analitici anonimizzati per ottimizzare il nostro sito web.<br><strong>Base:<\/strong> interesse legittimo.<\/p>\n\n    <h4>3.4 Obblighi legali<\/h4>\n    <p>Per l'adempimento degli obblighi amministrativi e fiscali.<br><strong>Base:<\/strong> obbligo di legge.<\/p>\n\n    <h4>3.5 Marketing (solo per consenso)<\/h4>\n    <p>Quando ci si iscrive per ricevere aggiornamenti o promozioni.<br><strong>Base:<\/strong> permesso.<\/p>\n\n    <h3>4. Periodi di conservazione<\/h3>\n    <ul>\n      <li>Moduli di contatto: fino a 12 mesi<\/li>\n      <li>Fatture e dati amministrativi: 7 anni (obbligo di conservazione legale)<\/li>\n      <li>Corrispondenza via e-mail: fino a 24 mesi<\/li>\n      <li>Dati analitici: secondo le impostazioni di Google Analytics<\/li>\n    <\/ul>\n\n    <h3>5. Sicurezza dei dati personali<\/h3>\n    <p>Adottiamo, tra le altre, le seguenti misure di sicurezza:<\/p>\n    <ul>\n      <li>Connessioni criptate (SSL)<\/li>\n      <li>Sistemi di accesso sicuri e protetti<\/li>\n      <li>Aggiornamenti regolari del software<\/li>\n      <li>Gestione degli accessi in base alle esigenze<\/li>\n      <li>Backup su server sicuri<\/li>\n    <\/ul>\n\n    <h3>6. Divulgazione a terzi<\/h3>\n    <p>Forniamo i vostri dati a terzi solo se necessario per i nostri servizi o se richiesto dalla legge. Con ciascuno di essi stipuliamo un accordo di trattamento, in cui si dichiara che i vostri dati non saranno utilizzati per altri scopi e saranno adeguatamente protetti.<\/p>\n\n    <p>Non vendiamo n\u00e9 affittiamo mai i vostri dati.<\/p>\n\n    <h3>7. I social media<\/h3>\n    <p>Il nostro sito web pu\u00f2 contenere collegamenti a piattaforme di social media. Quando si utilizzano queste piattaforme, si applica l'informativa sulla privacy della piattaforma in questione. Esse possono raccogliere dati come l'indirizzo IP e le informazioni sul browser. Non abbiamo alcuna influenza su questo aspetto.<\/p>\n\n    <h3>8. Diritti degli interessati<\/h3>\n    <p>Avete il diritto di:<\/p>\n    <ul>\n      <li>Ottenere l'accesso ai propri dati;<\/li>\n      <li>Correggete i vostri dati;<\/li>\n      <li>Richiedere la cancellazione dei propri dati;<\/li>\n      <li>Richiesta di limitazione del trattamento;<\/li>\n      <li>Obiezione al trattamento;<\/li>\n      <li>Ricevere e trasferire i vostri dati (portabilit\u00e0 dei dati);<\/li>\n      <li>Presentare un reclamo all'Autorit\u00e0 Garante per i dati personali.<\/li>\n    <\/ul>\n\n    <h3>9. Minori<\/h3>\n    <p>Il nostro sito web non \u00e8 rivolto a persone di et\u00e0 inferiore ai 16 anni. Se avete meno di 16 anni, siete pregati di utilizzare il sito web solo sotto la supervisione di un genitore o di un tutore.<\/p>\n\n    <h3>10. Biscotti<\/h3>\n    <p>Il nostro sito web utilizza i cookie per migliorare la funzionalit\u00e0 e l'esperienza dell'utente. Questo riguarda:<\/p>\n    <ul>\n      <li>Cookie funzionali<\/li>\n      <li>Cookie analitici (Google Analytics 4, anonimizzati)<\/li>\n    <\/ul>\n\n    <h4>Google Analytics 4<\/h4>\n    <p>Utilizziamo GA4 dove:<\/p>\n    <ul>\n      <li>Gli indirizzi IP sono anonimizzati<\/li>\n      <li>I dati non saranno utilizzati per scopi pubblicitari<\/li>\n      <li>I dati possono essere conservati al di fuori dell'UE<\/li>\n    <\/ul>\n    <p>\u00c8 possibile disattivare i cookie tramite le impostazioni del browser.<\/p>\n\n    <h3>11. Modifiche alla presente dichiarazione<\/h3>\n    <p>Potremmo modificare questa dichiarazione in caso di modifiche alla legislazione o ai nostri servizi. La versione pi\u00f9 recente \u00e8 sempre pubblicata sul nostro sito web.<\/p>\n\n    <h3>12. Domande o reclami<\/h3>\n    <p>Avete domande o volete segnalare un reclamo? Contattateci a:<\/p>\n    <p>\n      <strong>Rob v\/d Heuvel Auto<\/strong><br>\n      E-mail: <a href=\"mailto:ro***************@***il.com\" data-original-string=\"cDMkUuGCZNONKUlHEMxOcw==8e7bqQcJHMzWzEJr6Gklhti2y31H2U2peAuKl9yGCFqSCM=\" title=\"This contact has been encoded by Anti-Spam by CleanTalk. Click to decode. To finish the decoding make sure that JavaScript is enabled in your browser.\"><span \n                data-original-string='V5vbI2rMqJK9CLJN3Ag0Ww==8e7Q\/V8MykHE2E3wnoA+oMGXhRlEZcUyTk1YqPbB9OsSTI='\n                class='apbct-email-encoder'\n                title='This contact has been encoded by Anti-Spam by CleanTalk. Click to decode. To finish the decoding make sure that JavaScript is enabled in your browser.'>ro<span class=\"apbct-blur\">***************<\/span>@<span class=\"apbct-blur\">***<\/span>il.com<\/span><\/a><br>\n      Telefono: <a href=\"tel:0735477554\">073 - 5477554<\/a>\n    <\/p>\n    <p>Oppure presentare un reclamo all'Autorit\u00e0 Garante per i dati personali all'indirizzo: <a href=\"https:\/\/www.autoriteitpersoonsgegevens.nl\" target=\"_blank\" rel=\"noopener\">www.autoriteitpersoonsgegevens.nl<\/a><\/p>\n\n  <\/div>\n<\/section>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Privacy- en Cookieverklaring Rob v\/d Heuvel Auto\u2019s Bedrijvenweg 16, 5272 PB SINT-MICHIELSGESTEL KvK: 16052168 Contactpersoon: Rob Heuvel E-mail: in**@*********ts.com Telefoon: 06 &#8211; 40 99 42 48 Laatste update: December 2025 1. Inleiding Rob v\/d Heuvel Auto\u2019s hecht grote waarde aan de bescherming van uw privacy en persoonsgegevens. Wij verwerken uw gegevens uitsluitend volgens de AVG [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8851","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/heuvelparts.com\/it\/wp-json\/wp\/v2\/pages\/8851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heuvelparts.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/heuvelparts.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/heuvelparts.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/heuvelparts.com\/it\/wp-json\/wp\/v2\/comments?post=8851"}],"version-history":[{"count":7,"href":"https:\/\/heuvelparts.com\/it\/wp-json\/wp\/v2\/pages\/8851\/revisions"}],"predecessor-version":[{"id":8858,"href":"https:\/\/heuvelparts.com\/it\/wp-json\/wp\/v2\/pages\/8851\/revisions\/8858"}],"wp:attachment":[{"href":"https:\/\/heuvelparts.com\/it\/wp-json\/wp\/v2\/media?parent=8851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}